{"id":11107,"date":"2021-09-19T23:14:00","date_gmt":"2021-09-19T21:14:00","guid":{"rendered":"http:\/\/www.jimmy2.ch\/worldpress\/?p=11107"},"modified":"2021-12-11T20:48:38","modified_gmt":"2021-12-11T18:48:38","slug":"zu-hause-14-19-september-2021","status":"publish","type":"post","link":"https:\/\/www.jimmy2.ch\/worldpress\/2021\/09\/19\/zu-hause-14-19-september-2021\/","title":{"rendered":"Zu Hause 14. &#8211; 19. September 2021"},"content":{"rendered":"\n<p>Dienstag 14. September 2021<br>Eine warme Nacht. Keine Abk\u00fchlung. Nicht so angenehm wie im Wohnmobil. Darum bin ich wieder fr\u00fch munter. <br><br>Gestern sind einige Aktionen im Ricardo abgelaufen. Das muss ich ab arbeiten.<br><br>Um halb neun kommt Richi vorbei. Mit ihm habe ich ab und zu im Bereich Schwimmbad-Technik zusammengearbeitet. Er schaut, was er von meinem Rest an Schwimmbad-Artikel brauchen kann. Das eine oder andere kann er noch gebrauchen. Er wird gegen halb zehn nochmals vorbei kommen.<br><br>Um 9 Uhr kommt ein Ricardo-Kunde den Ergometer abholen. Klappt alles. So macht Ricardo Spass.<br><br>Dann ist auch schon Richi wieder da. Wir packen sein Auto voll. Meine Garage wird zusehends leer. Dann ist Zeit f\u00fcr Fr\u00fchst\u00fcck.<br><br>Mein Auto ist wieder voll mit Sachen zum Entsorgen. Also los. <br><br>Eigentlich wollte ich nun mit Christa einkaufen gehen. Aber das Entsorgen hat mich gepackt. Ich bringe nochmals eine Wagenladung voll zur Entsorgungsstation. <br><br>Um halb f\u00fcnf kommt jemand einen Bohrhammer abholen. <br><br>Und schon kommen unsere G\u00e4ste. Tochter Patricia und Schwiegersohn Flo kommen zum Nachtessen. Christa macht ganz feine panierte Schnitzel. Mit Reis. Schmeckt super. Es wird wieder ein sehr gem\u00fctlicher Abend. <br><br>Nachdem die K\u00fcche wieder sauber ist noch schnell die Tagesschau und die Wetterprognosen anschauen. Das war es dann f\u00fcr heute.<br><br><br><br>Mittwoch 15. September 2021<br>In der Nacht regnet es leicht. Aber es ist noch immer 18\u00b0. Ich k\u00fcmmere mich wieder um Ricardo. Die abgelaufenen Aktionen von gestern bearbeiten und neue Sachen einstellen. Noch etwas B\u00fcroarbeiten. Zahlungen m\u00fcssen auch wieder einmal gemacht werden. <br><br>Ich habe gestern mein Auto wieder mit Sachen f\u00fcr die Entsorgung gef\u00fcllt. So fahre ich wie gewohnt gegen halb elf zur Entsorgungsstelle.<br><br>Dann geht es auf die Post. Ricardo-Versand. Weiter zu meinen Eltern. Sie freuen sich auf \u00fcber unseren Besuch. Am Freitag komme ich wieder um einige Arbeiten auszuf\u00fchren. <br><br>Bevor es nach Hause geht einen kurzen Abstecher zu McDonald. Dann wieder einige Artikel bei Ricardo einstellen. Und noch ein paar Sachen ins Lager bringen.<br><br>Am Abend bekommen wir von unserem Makler eine schlechte Nachricht. F\u00fcr unsere Liegenschaft muss ein neuer K\u00e4ufer gesucht werden. Schade. Aber dadurch lassen wir uns nicht entmutigen. Unser Terminplan bleibt wie er ist.<br><br><br><br>Donnerstag 16. September 2021<br>Ein Regentag. Wie gewohnt:  Ricardo und Entsorgen. Um 14 Uhr habe ich einen Termin auf dem Notariat. Der Sitz meiner Firma muss verlegt werden. Auch wir m\u00fcssen uns dann noch ummelden. Wieder zu Hause kommt mein B\u00fcro dran. Alte Unterlagen ausmisten. Ein Schrank wird frei und bei Ricardo gestellt. Zuerst muss aber noch einiges umgestellt werden.<br><br>Ja und dann ist auch schon wieder Abend. Christa kocht etwas ganz feines. <br><br>Der PC im Wohnzimmer wird wieder einmal in Betrieb genommen, ges\u00e4ubert, Daten auf eine externe Harddisk gesichert und dann abgebaut. Er wird morgen entsorgt.<br><\/p>\n\n\n\n<p><br><br>Freitag 17. September 2021<br>Die N\u00e4chte werden l\u00e4nger. Um halb sieben ist es draussen noch dunkel. 14\u00b0.<br><br>Vor 2 Wochen konnte ich noch bei warmen 23\u00b0 und Sonnenschein auf dem Balkon sitzen. Diese Zeiten sind vorbei. Denke ich.<br><br>Bei Ricardo l\u00e4uft nicht viel. 18 Artikel sind zur Zeit eingestellt. Die ersten laufen am Montag um 13 Uhr ab. Ich hoffe, es kommt noch etwas Bewegung rein.<br><br>Heute muss ich mich von meiner Suchard-Dose trennen. Jahrelang stand sie bei mir auf dem Fr\u00fchst\u00fcckstisch.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.jimmy2.ch\/worldpress\/wp-content\/uploads\/2021\/09\/7955EFC3-4EB4-4787-B629-528C45119989-768x1024.jpeg\" alt=\"\" class=\"wp-image-11127\" srcset=\"https:\/\/www.jimmy2.ch\/worldpress\/wp-content\/uploads\/2021\/09\/7955EFC3-4EB4-4787-B629-528C45119989-768x1024.jpeg 768w, https:\/\/www.jimmy2.ch\/worldpress\/wp-content\/uploads\/2021\/09\/7955EFC3-4EB4-4787-B629-528C45119989-225x300.jpeg 225w, https:\/\/www.jimmy2.ch\/worldpress\/wp-content\/uploads\/2021\/09\/7955EFC3-4EB4-4787-B629-528C45119989-1152x1536.jpeg 1152w, https:\/\/www.jimmy2.ch\/worldpress\/wp-content\/uploads\/2021\/09\/7955EFC3-4EB4-4787-B629-528C45119989-1536x2048.jpeg 1536w, https:\/\/www.jimmy2.ch\/worldpress\/wp-content\/uploads\/2021\/09\/7955EFC3-4EB4-4787-B629-528C45119989-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p><br>Um 10 Uhr habe ich einen Termin bei meinen Eltern. Waschmaschine und Trocken bekommen einen neuen Platz. Es wurde alles schon vorbereitet. Ich muss nur die Maschinen z\u00fcgeln und neu anschliessen.<br><br>Um halb acht ruft Frank0012 an. Er hat bei Ricardo verschiedene Sachen ersteigert. Er komme so gegen 10 Uhr diese Abholen, meint er.<br><br>Das bringt meinen Plan etwas durcheinander. Ich bereite die Sachen vor die ich bei meinen Eltern brauche. Noch etwas f\u00fcr die Entsorgung einladen. Und schon steht Frank0012 vor der T\u00fcre. Ich helfe ihm beim einladen. Passt alles rein bis auf das Schwerlast-Regal. Das kommt er sp\u00e4ter abholen. <br><br>Nun rasch zur Entsorgung und zu meinen Eltern. Ich rufe an, das es etwas sp\u00e4ter wird. Um viertel vor elf beginne ich mit dem Umbau. Geht einfacher als gedacht. Um halb zw\u00f6lf sind die Maschinen am neuen Ort. Das Abwasserrohr kann ich anpassen. F\u00fcr den Wasseranschluss ben\u00f6tige ich einen \u201ePanzerschlauch\u201c. Diesen und noch ein paar andere Sachen hole ich im OBI. Schon \u00fcber 2 Monate war ich in keinem Baucenter mehr. Muss mich zuerst neu orientieren. Aber zu allererst brauche ich einen Kaffee und etwas zu Essen. Beim Eingang zum Restaurant muss ich mein Covit-Zertifikat und den Ausweis zeigen. Wobei, wenn ich draussen sitze w\u00e4re das nicht notwendig. Aber ich will wissen ob es funktioniert. Es funktioniert. <\/p>\n\n\n\n<p>Das Essen und der Einkauf sind schell erledigt. Um halb eins bin ich schon wieder zur\u00fcck. Passt alles. Es folgt ein Probelauf der Waschmaschine. Das Ablaufrohr getropft. Eigentlich kein Wunder. Die Dichtungen der streckbaren Rohre sind \u00fcber 20 Jahre alt. Ich demontiere ein kurzes St\u00fcck Abwasserrohr, reinige alles und stecke es wieder zusammen. Nun funktioniert es. Ich packe meine Sachen zusammen und verabschiede mich bis morgen Samstag oder Sonntag. Dann muss ich noch einen Halte-Griff bei der Badewanne montieren. Heute habe ich keine Schlagbohrmaschine dabei.<br><br>Es ist ein wundersch\u00f6ner und warmer Tag geworden. Christa fragen ob wir spazieren gehen. Geht nicht. Gabriela, eine Camperin aus unserer Zeit von Horw kommt zum Kaffee. Ich bin kurz dabei. Dann zieht es mich in die Garage. Holz schneiden und Regale abbauen. <br><br>Um halb f\u00fcnf ist Schluss. Ich brauche eine Dusche. Unbedingt. Christa f\u00e4hrt noch Einkaufen. Morgen haben wir G\u00e4ste. <br><br>Das Nachtessen k\u00f6nnen wir auf dem Balkon geniessen. Das h\u00e4tte ich heute Morgen nicht gedacht. Aber so warm wie vor 2 Wochen ist es nicht mehr.<br><br><br><br>Samstag 4. September 2021<br>Der Tag beginnt mit Sonne. Aber nur 10\u00b0. Etwas frisch f\u00fcr kurze Hosen. Aber ich bin ja vorerst drinnen.<br><br>F\u00fcr 9 Uhr hat sich eine Ricardo-Kunde angesagt. Bin gespannt wann er auftaucht. Ja er kommt p\u00fcnktlich.<br><br>Ich nutze den inzwischen sonnigen Tag um Fotos von Artikeln zu machen welche ich umgehend bei Ricardo zur Versteigerung anbiete.<br><br>Gegen Mittag ein kurzer Einkauf im Volkiland. Nach einer guten 3\/4 Stunde sind wir wieder zu Hause. So macht Einkaufen keinen Spass. <br><br>Das Wetter ist herrlich. Christa macht einen vielleicht letzten Schwumm im Pool. Ich kann leider nicht, da meine Wunden noch nicht soweit verheilt sind. <br><br>Nun verzieht sich Christa in die K\u00fcche. Ich zerlege die Truhe f\u00fcr die Kissen der Sitzgruppe die wir schon verkauft haben. F\u00fcr halb f\u00fcnf hat sich noch eine Ricardo-Kunde angemeldet. Geht alles kurzfristig \u00fcber SMS. Auch der ist p\u00fcnktlich. <br><br>Nun ab unter die Dusche. Und schon ist es Zeit unsere G\u00e4ste zu empfangen. Wir k\u00f6nnen den ganzen Abend auf dem Balkon verbringen. Der Grill wird in Betrieb genommen. Das Essen schmeckt vorz\u00fcglich. Auch Christas Nachtisch. Super. <br><br>Die Zeit vergeht. Es wird frisch. Kurz vor zehn Uhr verabschieden wir uns Carmen und Thomi. Als wir vor \u00fcber 20 Jahren als wir nach Br\u00fcttisellen gezogen sind, haben wir Sie kennengelernt.  Ab und zu etwas unternommen. Vor allen Christa und Carmen. Die M\u00e4dchen waren in etwa im gleichen Alter.<br><br><br><br>Sonntag 19. September 2021<br>Wir angek\u00fcndigt ein tr\u00fcber Tag. Gleich nach dem Aufstehen beginnen wir mit dem Einpacken von Bildern die wir in unserer Wohnung aufgestellt haben. Einmal muss es ja sein. Wir k\u00f6nnen nicht bis zum letzten Tag warten. Da wird es dann noch anderes zu erledigen geben.<br><br>Um halb zw\u00f6lf sind wir bei meinen Eltern. Ich muss noch den Haltegriffe bei der Badewanne anbringen. Christa bereitet in dieser Zeit ein kleines Mittagessen zu. <br><br>Nach 2 Stunden geht es wieder heimw\u00e4rts. In der Zwischenzeit hat der Regen eingesetzt. Nach einer Kaffeepause werden weitere Bilder eingepackt. Sie werden eingelagert. <br><br>Um f\u00fcnf Uhr kommt ein Ricardo-Kunde die W\u00e4rmekabine abzuholen. Leider ist sein Auto zu klein. Obwohl er es ausgemessen hat. Es fehlen 2 cm. Damit dieser Deal abgeschlossen werden kann, laden wir die W\u00e4rmekabine kurzerhand in meinen Renault Trafic und fahren nach Beringen SH.<br><br>Es regnet und hat viel Verkehr. Trotzdem geniesse ich die Fahrt in mir bekannte Gebiete. Um sieben Uhr bin ich wieder zu Hause. Christa ist noch mit dem Aussortieren von Kleidern besch\u00e4ftigt. <br><br>Es folgt ein kleiner Snack, Tatort und Anne Will. In einer Woche sind in Deutschland Wahlen. Bin gespannt wer neuer Kanzler(in) wird. <br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dienstag 14. September 2021Eine warme Nacht. Keine Abk\u00fchlung. Nicht so angenehm wie im Wohnmobil. Darum bin ich wieder fr\u00fch munter. Gestern sind einige Aktionen im Ricardo abgelaufen. Das muss ich ab arbeiten. Um halb neun kommt Richi vorbei. Mit ihm &hellip; <a href=\"https:\/\/www.jimmy2.ch\/worldpress\/2021\/09\/19\/zu-hause-14-19-september-2021\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[72],"tags":[677,587],"class_list":["post-11107","post","type-post","status-publish","format-standard","hentry","category-schweiz","tag-entsorgen","tag-zu-hause"],"_links":{"self":[{"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/posts\/11107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/comments?post=11107"}],"version-history":[{"count":4,"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/posts\/11107\/revisions"}],"predecessor-version":[{"id":11128,"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/posts\/11107\/revisions\/11128"}],"wp:attachment":[{"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/media?parent=11107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/categories?post=11107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jimmy2.ch\/worldpress\/wp-json\/wp\/v2\/tags?post=11107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}